{"id":1327,"date":"2021-05-19T17:07:53","date_gmt":"2021-05-19T16:07:53","guid":{"rendered":"https:\/\/www.la-vitrolle.fr\/vin\/situation-contact-vin-de-pays-domaine-de-la-vitrolle\/"},"modified":"2024-03-28T16:03:15","modified_gmt":"2024-03-28T15:03:15","slug":"location-contact-vin-de-pays-domaine-de-la-vitrolle","status":"publish","type":"page","link":"https:\/\/www.la-vitrolle.fr\/vin\/en\/location-contact-vin-de-pays-domaine-de-la-vitrolle\/","title":{"rendered":"Location-Contact"},"content":{"rendered":"<div  class='av_gmaps_sc_main_wrap av_gmaps_main_wrap '><div id='av_gmap_0' class='avia-google-map-container avia-google-map-sc av_gmaps_show_unconditionally av-no-fallback-img ' data-mapid='av_gmap_0'  style='height: 400px;'><a class=\"av_gmaps_browser_disabled av_text_confirm_link av_text_confirm_link_visible\" href=\"https:\/\/www.google.com\/maps\/search\/?api=1&#038;query=44.8952778,0.903611111\" target=\"_blank\">Maps were disabled by the visitor on this site. Click to open the map in a new window.<\/a><\/div><\/div>\n<div id='av_section_1'  class='avia-section av-7wxehj-0480c172dbc59a9b28bc01ebb5143006 main_color avia-section-default avia-no-border-styling  avia-builder-el-1  el_after_av_google_map  avia-builder-el-last  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1327'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-5a4567-4ad630f041dd1190cbdd180c1e491dea av_one_half  avia-builder-el-2  el_before_av_one_half  avia-builder-el-first  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k1bv8n46-ac91b143d24eaa4d824656d125c3e3f8\">\n#top .av-special-heading.av-k1bv8n46-ac91b143d24eaa4d824656d125c3e3f8{\npadding-bottom:10px;\ncolor:#a1609e;\nfont-size:38px;\n}\nbody .av-special-heading.av-k1bv8n46-ac91b143d24eaa4d824656d125c3e3f8 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-k1bv8n46-ac91b143d24eaa4d824656d125c3e3f8 .av-special-heading-tag{\nfont-size:38px;\n}\n.av-special-heading.av-k1bv8n46-ac91b143d24eaa4d824656d125c3e3f8 .special-heading-inner-border{\nborder-color:#a1609e;\n}\n.av-special-heading.av-k1bv8n46-ac91b143d24eaa4d824656d125c3e3f8 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-k1bv8n46-ac91b143d24eaa4d824656d125c3e3f8 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-k1bv8n46-ac91b143d24eaa4d824656d125c3e3f8 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-k1bv8n46-ac91b143d24eaa4d824656d125c3e3f8 av-special-heading-h2 custom-color-heading blockquote modern-quote  avia-builder-el-3  el_before_av_iconlist  avia-builder-el-first  av-inherit-size av-linked-heading'><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >To contact us<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k18241oa-964347601513701793a5ffc15ddc83c6\">\n#top .avia-icon-list-container.av-k18241oa-964347601513701793a5ffc15ddc83c6 .iconlist_icon{\nfont-size:20px;\n}\n#top .avia-icon-list-container.av-k18241oa-964347601513701793a5ffc15ddc83c6 .iconlist_icon svg:first-child{\nheight:20px;\nwidth:20px;\n}\n#top #wrap_all .avia-icon-list-container.av-k18241oa-964347601513701793a5ffc15ddc83c6 .av_iconlist_title{\nfont-size:20px;\n}\n<\/style>\n<div  class='avia-icon-list-container av-k18241oa-964347601513701793a5ffc15ddc83c6  avia-builder-el-4  el_after_av_heading  el_before_av_image '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-small av-k18241oa-964347601513701793a5ffc15ddc83c6 avia-iconlist-animate'>\n<li><div class='iconlist_icon av-echnb-de3ebddcbaef1fbf66d958e916e732ae avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue821' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: SCEA DOMAINE DE LA VITROLLE \"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >SCEA DOMAINE DE LA VITROLLE <\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-anpjz-ddbafebf1821740dac800c5a188b9cbe avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue841' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: F-24510 LIMEUIL - FRANCE\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >F-24510 LIMEUIL - FRANCE<\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-gh11r-8ff894b60794853526414727119333d3 avia-font-awesome avia-iconfont avia-font-awesome'><span class='av-icon-char' data-av_icon='\ue800' data-av_iconfont='awesome' aria-hidden=\"true\"><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: &lt;a href=&quot;tel:33.553615858&quot;&gt;+33 (0)553 615 858&lt;\/a&gt;\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href=\"tel:33.553615858\">+33 (0)553 615 858<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-8ph07-e2ad0ec27f43508257266aa5a8188d72 avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue805' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: &lt;a href=&quot;mailto:lavitrolle.chai@orange.fr&quot;&gt;lavitrolle.chai@orange.fr&lt;\/a&gt;\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" ><a href=\"mailto:lavitrolle.chai@orange.fr\">lavitrolle.chai@orange.fr<\/a><\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-8ph07-fff8e98d345930dd49283efe714815c3 avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue842' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: 44\u00b0 53\u2032 43\u2033 N \u2013 0\u00b0 54\u2032 13\u2033 E\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >44\u00b0 53\u2032 43\u2033 N \u2013 0\u00b0 54\u2032 13\u2033 E<\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k1935k0r-aaa20f4839fa0ec33bf23fbc14bccab5\">\n.avia-image-container.av-k1935k0r-aaa20f4839fa0ec33bf23fbc14bccab5 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-k1935k0r-aaa20f4839fa0ec33bf23fbc14bccab5 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-k1935k0r-aaa20f4839fa0ec33bf23fbc14bccab5 av-styling- avia-align-center  avia-builder-el-5  el_after_av_iconlist  el_before_av_textblock '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-1264 avia-img-lazy-loading-not-1264 avia_image ' src=\"https:\/\/www.la-vitrolle.fr\/vin\/wp-content\/uploads\/2021\/09\/slide-vignoble-00.jpg\" alt='Wines from the P\u00e9rigord region' title='Wines from the P\u00e9rigord region'  height=\"600\" width=\"900\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.la-vitrolle.fr\/vin\/wp-content\/uploads\/2021\/09\/slide-vignoble-00.jpg 900w, https:\/\/www.la-vitrolle.fr\/vin\/wp-content\/uploads\/2021\/09\/slide-vignoble-00-300x200.jpg 300w, https:\/\/www.la-vitrolle.fr\/vin\/wp-content\/uploads\/2021\/09\/slide-vignoble-00-768x512.jpg 768w, https:\/\/www.la-vitrolle.fr\/vin\/wp-content\/uploads\/2021\/09\/slide-vignoble-00-705x470.jpg 705w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-knq0xq3n-70039263e7da6b737911d629ea8e160b '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><em><strong>Domaine de La Vitrolle: Vin de Pays du P\u00e9rigord IGP (Protected geographical indication).<\/strong><br \/>\nRed wine Domaine de La Vitrolle, Red wine Demoiselle de Limeuil, Ros\u00e9 wine Ros\u00e9 des Pierrailles, White wine dry and White medium dry Chevalier de la Demoiselle.<\/em><\/p>\n<\/div><\/section><\/p><\/div><div  class='flex_column av-5a4567-7db9d4f4819aa1ef194b68e79279f87f av_one_half  avia-builder-el-7  el_after_av_one_half  avia-builder-el-last  flex_column_div  '     ><form action=\"https:\/\/www.la-vitrolle.fr\/vin\/en\/location-contact-vin-de-pays-domaine-de-la-vitrolle\/\" method=\"post\" data-fields-with-error=\"Found errors in the following field(s):\" class=\"avia_ajax_form av-form-labels-visible   avia-builder-el-8  avia-builder-el-no-sibling   \" data-avia-form-id=\"1\" data-avia-redirect='' ><fieldset><p class='  first_form  form_element form_element_half' id='element_avia_1_1'><label for=\"avia_1_1\">Name <abbr class=\"required\" title=\"required\">*<\/abbr><\/label> <input name=\"avia_1_1\" class=\"text_input is_empty\" type=\"text\" id=\"avia_1_1\" value=\"\" \/><\/p><p class='  form_element form_element_half' id='element_avia_2_1'><label for=\"avia_2_1\">Telephone <abbr class=\"required\" title=\"required\">*<\/abbr><\/label> <input name=\"avia_2_1\" class=\"text_input is_empty\" type=\"text\" id=\"avia_2_1\" value=\"\" \/><\/p><p class='  first_form  form_element form_fullwidth' id='element_avia_3_1'><label for=\"avia_3_1\">Email <abbr class=\"required\" title=\"required\">*<\/abbr><\/label> <input name=\"avia_3_1\" class=\"text_input is_email\" type=\"text\" id=\"avia_3_1\" value=\"\" \/><\/p><p class='  first_form  form_element form_fullwidth' id='element_avia_4_1'><label for=\"avia_4_1\" class=\"textare_label hidden textare_label_avia_4_1\">Message <abbr class=\"required\" title=\"required\">*<\/abbr><\/label><textarea  name=\"avia_4_1\" class=\"text_area is_empty\" cols=\"40\" rows=\"7\" id=\"avia_4_1\" ><\/textarea><\/p><p class='  first_form  form_element form_fullwidth' id='element_avia_5_1'><input  name=\"avia_5_1\" class=\"input_checkbox is_empty\" type=\"checkbox\" id=\"avia_5_1\" value=\"true\"\/><label class=\"input_checkbox_label\" for=\"avia_5_1\">By submitting this form, I agree that the information entered will be used to allow the follow-up resulting from my request. <abbr class=\"required\" title=\"required\">*<\/abbr><\/label><\/p><p class=\"hidden\"><input type=\"text\" name=\"avia_6_1\" class=\"hidden \" id=\"avia_6_1\" value=\"\" \/><\/p><div id='avia_7_1' class='av-recaptcha-area  first_form  form_element form_fullwidth '  data-container_class=\"\" data-custom_class=\"\" data-context=\"av_contact_form\" data-token_input=\"av_recaptcha_token\" data-version=\"avia_recaptcha_v3\" data-theme=\"light\" data-size=\"normal\" data-score=\"0.5\" data-text_to_preview=\"\" data-value=\"\"><div class=\"av-google-badge-message hidden\">This site is protected by reCAPTCHA and the Google <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a> and <a href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\" rel=\"noopener noreferrer\">Terms of Service<\/a> apply.<\/div><\/div><p class=\"form_element \"><input type=\"hidden\" value=\"1\" name=\"avia_generated_form1\" \/><input type=\"submit\" value=\"Send to Domaine de La Vitrolle\" class=\"button\"  data-sending-label=\"Sending\"\/><\/p><\/fieldset><div class=\"avia-disabled-form\">This contact form is deactivated because you refused to accept Google reCaptcha service which is necessary to validate any messages sent by the form.<\/div><\/form><div id=\"ajaxresponse_1\" class=\"ajaxresponse ajaxresponse_1 hidden\"><\/div><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1327'><div class='entry-content-wrapper clearfix'>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1327","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact or buy Domaine de La Vitrolle wine from P\u00e9rigord IGP in Dordogne<\/title>\n<meta name=\"description\" content=\"Sale of vin de pays du P\u00e9rigord IGP (Protected geographical indication) region to the Domaine de la Vitrolle in Dordogne. Contact us for advice, to taste in the cellar or to buy one of our vin de pays du P\u00e9rigord: Domaine de La Vitrolle red wine, Demoiselle de Limeuil red wine, Pierrailles ros\u00e9 wine, Chevalier de la Demoiselle white wine dry and white wine medium dry.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.la-vitrolle.fr\/vin\/en\/location-contact-vin-de-pays-domaine-de-la-vitrolle\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact or buy Domaine de La Vitrolle wine from P\u00e9rigord IGP in Dordogne\" \/>\n<meta property=\"og:description\" content=\"Sale of vin de pays du P\u00e9rigord IGP (Protected geographical indication) region to the Domaine de la Vitrolle in Dordogne. Contact us for advice, to taste in the cellar or to buy one of our vin de pays du P\u00e9rigord: Domaine de La Vitrolle red wine, Demoiselle de Limeuil red wine, Pierrailles ros\u00e9 wine, Chevalier de la Demoiselle white wine dry and white wine medium dry.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.la-vitrolle.fr\/vin\/en\/location-contact-vin-de-pays-domaine-de-la-vitrolle\/\" \/>\n<meta property=\"og:site_name\" content=\"Domaine de La Vitrolle, vin de pays du P\u00e9rigord\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-28T15:03:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/en\\\/location-contact-vin-de-pays-domaine-de-la-vitrolle\\\/\",\"url\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/en\\\/location-contact-vin-de-pays-domaine-de-la-vitrolle\\\/\",\"name\":\"Contact or buy Domaine de La Vitrolle wine from P\u00e9rigord IGP in Dordogne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/#website\"},\"datePublished\":\"2021-05-19T16:07:53+00:00\",\"dateModified\":\"2024-03-28T15:03:15+00:00\",\"description\":\"Sale of vin de pays du P\u00e9rigord IGP (Protected geographical indication) region to the Domaine de la Vitrolle in Dordogne. Contact us for advice, to taste in the cellar or to buy one of our vin de pays du P\u00e9rigord: Domaine de La Vitrolle red wine, Demoiselle de Limeuil red wine, Pierrailles ros\u00e9 wine, Chevalier de la Demoiselle white wine dry and white wine medium dry.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/en\\\/location-contact-vin-de-pays-domaine-de-la-vitrolle\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/en\\\/location-contact-vin-de-pays-domaine-de-la-vitrolle\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/en\\\/location-contact-vin-de-pays-domaine-de-la-vitrolle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Location-Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/#website\",\"url\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/\",\"name\":\"Domaine de La Vitrolle, vin de pays du P\u00e9rigord\",\"description\":\"Location de manoir en Dordogne P\u00e9rigord\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/#organization\",\"name\":\"Domaine de La Vitrolle - Vin de pays du P\u00e9rigord\",\"url\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-vitrolle-vin-230px.jpg\",\"contentUrl\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-vitrolle-vin-230px.jpg\",\"width\":230,\"height\":125,\"caption\":\"Domaine de La Vitrolle - Vin de pays du P\u00e9rigord\"},\"image\":{\"@id\":\"https:\\\/\\\/www.la-vitrolle.fr\\\/vin\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact or buy Domaine de La Vitrolle wine from P\u00e9rigord IGP in Dordogne","description":"Sale of vin de pays du P\u00e9rigord IGP (Protected geographical indication) region to the Domaine de la Vitrolle in Dordogne. Contact us for advice, to taste in the cellar or to buy one of our vin de pays du P\u00e9rigord: Domaine de La Vitrolle red wine, Demoiselle de Limeuil red wine, Pierrailles ros\u00e9 wine, Chevalier de la Demoiselle white wine dry and white wine medium dry.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.la-vitrolle.fr\/vin\/en\/location-contact-vin-de-pays-domaine-de-la-vitrolle\/","og_locale":"en_US","og_type":"article","og_title":"Contact or buy Domaine de La Vitrolle wine from P\u00e9rigord IGP in Dordogne","og_description":"Sale of vin de pays du P\u00e9rigord IGP (Protected geographical indication) region to the Domaine de la Vitrolle in Dordogne. Contact us for advice, to taste in the cellar or to buy one of our vin de pays du P\u00e9rigord: Domaine de La Vitrolle red wine, Demoiselle de Limeuil red wine, Pierrailles ros\u00e9 wine, Chevalier de la Demoiselle white wine dry and white wine medium dry.","og_url":"https:\/\/www.la-vitrolle.fr\/vin\/en\/location-contact-vin-de-pays-domaine-de-la-vitrolle\/","og_site_name":"Domaine de La Vitrolle, vin de pays du P\u00e9rigord","article_modified_time":"2024-03-28T15:03:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.la-vitrolle.fr\/vin\/en\/location-contact-vin-de-pays-domaine-de-la-vitrolle\/","url":"https:\/\/www.la-vitrolle.fr\/vin\/en\/location-contact-vin-de-pays-domaine-de-la-vitrolle\/","name":"Contact or buy Domaine de La Vitrolle wine from P\u00e9rigord IGP in Dordogne","isPartOf":{"@id":"https:\/\/www.la-vitrolle.fr\/vin\/#website"},"datePublished":"2021-05-19T16:07:53+00:00","dateModified":"2024-03-28T15:03:15+00:00","description":"Sale of vin de pays du P\u00e9rigord IGP (Protected geographical indication) region to the Domaine de la Vitrolle in Dordogne. Contact us for advice, to taste in the cellar or to buy one of our vin de pays du P\u00e9rigord: Domaine de La Vitrolle red wine, Demoiselle de Limeuil red wine, Pierrailles ros\u00e9 wine, Chevalier de la Demoiselle white wine dry and white wine medium dry.","breadcrumb":{"@id":"https:\/\/www.la-vitrolle.fr\/vin\/en\/location-contact-vin-de-pays-domaine-de-la-vitrolle\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.la-vitrolle.fr\/vin\/en\/location-contact-vin-de-pays-domaine-de-la-vitrolle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.la-vitrolle.fr\/vin\/en\/location-contact-vin-de-pays-domaine-de-la-vitrolle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.la-vitrolle.fr\/vin\/en\/"},{"@type":"ListItem","position":2,"name":"Location-Contact"}]},{"@type":"WebSite","@id":"https:\/\/www.la-vitrolle.fr\/vin\/#website","url":"https:\/\/www.la-vitrolle.fr\/vin\/","name":"Domaine de La Vitrolle, vin de pays du P\u00e9rigord","description":"Location de manoir en Dordogne P\u00e9rigord","publisher":{"@id":"https:\/\/www.la-vitrolle.fr\/vin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.la-vitrolle.fr\/vin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.la-vitrolle.fr\/vin\/#organization","name":"Domaine de La Vitrolle - Vin de pays du P\u00e9rigord","url":"https:\/\/www.la-vitrolle.fr\/vin\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.la-vitrolle.fr\/vin\/#\/schema\/logo\/image\/","url":"https:\/\/www.la-vitrolle.fr\/vin\/wp-content\/uploads\/2021\/09\/logo-vitrolle-vin-230px.jpg","contentUrl":"https:\/\/www.la-vitrolle.fr\/vin\/wp-content\/uploads\/2021\/09\/logo-vitrolle-vin-230px.jpg","width":230,"height":125,"caption":"Domaine de La Vitrolle - Vin de pays du P\u00e9rigord"},"image":{"@id":"https:\/\/www.la-vitrolle.fr\/vin\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.la-vitrolle.fr\/vin\/en\/wp-json\/wp\/v2\/pages\/1327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.la-vitrolle.fr\/vin\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.la-vitrolle.fr\/vin\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.la-vitrolle.fr\/vin\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.la-vitrolle.fr\/vin\/en\/wp-json\/wp\/v2\/comments?post=1327"}],"version-history":[{"count":0,"href":"https:\/\/www.la-vitrolle.fr\/vin\/en\/wp-json\/wp\/v2\/pages\/1327\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.la-vitrolle.fr\/vin\/en\/wp-json\/wp\/v2\/media?parent=1327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}